{"id":978,"date":"2019-04-11T10:39:38","date_gmt":"2019-04-11T10:39:38","guid":{"rendered":"http:\/\/solovariz.es\/?page_id=978"},"modified":"2026-03-17T08:59:54","modified_gmt":"2026-03-17T08:59:54","slug":"doctor-juan-jose-mengual","status":"publish","type":"page","link":"https:\/\/solovariz.es\/es\/doctor-juan-jose-mengual\/","title":{"rendered":"Doctor Juan Jose Mengual"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"978\" class=\"elementor elementor-978\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdf125c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdf125c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e49f4b\" data-id=\"6e49f4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab8514 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5ab8514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Doctor Juan Jos\u00e9 Mengual<\/h2><p>Miembro fundador en Centro De Estudios Flebol\u00f3gicos y Grupo Solovariz<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb3e449 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb3e449\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-308af7d\" data-id=\"308af7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bba735 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"4bba735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/1.jpg);\" role=\"img\" aria-label=\"1\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tHistoria\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEl Dr. Juan Jos\u00e9 Mengual comenz\u00f3 a estudiar Medicina en la Universidad Complutense de Madrid, en 1970..\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#historia\">\n\t\t\t\t\t\tSeguir leyendo\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7dd8985\" data-id=\"7dd8985\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25d3953 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"25d3953\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/3-SOLOVARIZ-en-Saber-Vivir-en-La-ma\u00f1ana-de-la-1-YouTube-Google-Chrome-1024x553.jpg);\" role=\"img\" aria-label=\"3 SOLOVARIZ en Saber Vivir en La ma\u00f1ana de la 1 - YouTube - Google Chrome\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tCentro de Estudios Flebol\u00f3gicos\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEspec\u00edficamente en el a\u00f1o 1993, se encontraron frente al m\u00e9todo del tratamiento de varices con espuma..\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#centro\">\n\t\t\t\t\t\tSeguir leyendo\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fdbc756\" data-id=\"fdbc756\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2de0e2 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"b2de0e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2018\/03\/profesionales-1024x576.jpg);\" role=\"img\" aria-label=\"profesionales\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSolovariz\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLa idea de SOLOVARIZ parti\u00f3 del Doctor Mengual como un centro de formaci\u00f3n para todo profesional..\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tSeguir leyendo\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e458d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e458d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c263255\" data-id=\"c263255\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-28d7fec\" data-id=\"28d7fec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ea58b elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"77ea58b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2018\/02\/Untitled-1-1-1024x574.png);\" role=\"img\" aria-label=\"Untitled-1-1.png\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tBlog\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tAccede a los \u00faltimos art\u00edculos del Doctor Juan Jos\u00e9 Mengual\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#blog\">\n\t\t\t\t\t\tSeguir leyendo\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a6c8a89\" data-id=\"a6c8a89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f75028 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"8f75028\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/2-SOLOVARIZ-en-Madrid-Directo-Telemadrid-YouTube-Google-Chrome-300x162.jpg);\" role=\"img\" aria-label=\"2 SOLOVARIZ en Madrid Directo - Telemadrid - YouTube - Google Chrome\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tApariciones en televisi\u00f3n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tVisita las apariciones del Doctor Juan Jos\u00e9 Mengual en televisi\u00f3n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#tv\">\n\t\t\t\t\t\tSeguir leyendo\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fff742e\" data-id=\"fff742e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ddcce5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ddcce5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3178e61\" data-id=\"3178e61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67baa47 elementor-widget elementor-widget-spacer\" data-id=\"67baa47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da24ede elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da24ede\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43a4c02\" data-id=\"43a4c02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-836f7ec elementor-widget elementor-widget-html\" data-id=\"836f7ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"historia\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3139f6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e3139f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Historia<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b9a9a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b9a9a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a24037\" data-id=\"0a24037\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d6208f elementor-widget elementor-widget-text-editor\" data-id=\"1d6208f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <strong>Dr. Juan Jos\u00e9 Mengual<\/strong> comenz\u00f3 a estudiar <strong>Medicina<\/strong> en la <strong>Universidad Complutense<\/strong> de<strong> Madrid<\/strong>, en 1970. A lo largo de sus <strong>a\u00f1os de estudio<\/strong> siempre se sinti\u00f3 atra\u00eddo por los temas relacionados con <strong>tratamientos novedosos<\/strong> y el <strong>sistema circulatorio<\/strong> del cuerpo humano. Se grad\u00fao en el a\u00f1o 1976, y a partir de all\u00ed comenz\u00f3 <strong>su trayectoria<\/strong> hasta llegar a convertirse en el <strong>pionero del tratamiento de varices sin cirug\u00eda en Espa\u00f1a<\/strong>.<\/p><p>Una vez terminados sus estudios en la<strong> Universidad Complutense<\/strong> incursion\u00f3 en tratamientos que se conocen hoy en d\u00eda como alternativos: especializ\u00e1ndose en tratamiento neurales (a trav\u00e9s del uso de la aguja para tratar diferentes patolog\u00edas) y homeop\u00e1ticos. Se enfrent\u00f3 a <strong>pacientes cr\u00f3nicos<\/strong> ya que eran los que buscaban otras alternativas cuando ya hab\u00edan probado todo lo dem\u00e1s. Consistiendo en un <strong>reto con cada paciente<\/strong>, lo que despert\u00f3 su <strong>curiosidad<\/strong> por <strong>t\u00e9cnicas<\/strong> y <strong>m\u00e9todos innovadores<\/strong>.<\/p><p>A su vez, se integr\u00f3 a un grupo de amigos <strong>m\u00e9dicos curiosos<\/strong> de los temas relacionados con la medicina y con los cu\u00e1les compart\u00eda <strong>experiencias sobre las varices<\/strong> y los <strong>nuevos avances<\/strong> que se iban presentando.<\/p><p>El <strong>Doctor Mengual<\/strong> se percat\u00f3 que las <strong>varices constitu\u00edan un problema muy com\u00fan<\/strong> entre mujeres y hombres y ya se empezaban a utilizar <strong>nuevas t\u00e9cnicas<\/strong> para tratarlas y<strong> sustituir a la cirug\u00eda<\/strong> como <strong>\u00fanica alternativa<\/strong>, pero las personas segu\u00edan someti\u00e9ndose a intervenciones para <strong>eliminar las varices<\/strong> grandes en <strong>venas principales<\/strong> como la <strong>safena<\/strong>.<\/p><p>Espec\u00edficamente en el a\u00f1o 1993, se encontraron frente al <strong>m\u00e9todo del tratamiento de varices<\/strong> con espuma gracias al Dr. Cabrera y a partir de ese a\u00f1o<strong> comenz\u00f3 a desarrollar la t\u00e9cnica<\/strong>, de la que <strong>no se sab\u00eda nada hasta el momento<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f85f28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f85f28\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-faf58b5\" data-id=\"faf58b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f5c92 elementor-widget elementor-widget-html\" data-id=\"46f5c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"centro\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8f3a20 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b8f3a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro de Estudios Flebol\u00f3gicos\u200b<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89752df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89752df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8769b29\" data-id=\"8769b29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6466014 elementor-widget elementor-widget-text-editor\" data-id=\"6466014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De all\u00ed nace la idea del <strong>Centro de Estudios Flebol\u00f3gicos<\/strong>, conformado por los doctores <strong>Juan Jos\u00e9 Mengual<\/strong> y <strong>Juan Jos\u00e9 M\u00e1rquez<\/strong>, miembros de la <strong>Sociedad Espa\u00f1ola de Angiolog\u00eda y Cirug\u00eda Vascular<\/strong>, donde deciden desarrollar este<strong> tipo de tratamiento<\/strong>, siendo los <strong>pioneros en Madrid<\/strong> en la <strong>eliminaci\u00f3n de las varices con microespuma<\/strong>, llegando a patentar el<strong> proceso TRV<\/strong> (Tratamiento Radical de Varices) que utilizan \u00fanicamente ellos como los <strong>precursores de este m\u00e9todo<\/strong>.<\/p><h3><strong>Como la t\u00e9cnica de la microespuma era muy nueva, le llev\u00f3 a\u00f1os mejorarla y perfeccionarla:<\/strong><\/h3><ul><li>Unos tres a\u00f1os desarrollar el c\u00f3mo, el por qu\u00e9, la cantidad exacta que deb\u00edan utilizar,<\/li><li>Cambiaron el vendaje por medias de comprensi\u00f3n hasta desarrollar un proceso de tratamiento que se pudo sistematizar.<\/li><\/ul><p>A partir de all\u00ed s\u00f3lo hubo <strong>mejoras<\/strong> y poco a poco <strong>m\u00e1s personas<\/strong> se dieron cuenta del <strong>avance<\/strong> que esto podr\u00eda traer para <strong>los tratamientos flebol\u00f3gicos<\/strong>. A pesar de tener un <strong>inicio complicado<\/strong> debido a la <strong>falta de material e investigaci\u00f3n<\/strong> sobre este tema, los<strong> pacientes<\/strong> <strong>fueron los primeros<\/strong> que empezaron a aceptarlo debido a que con <strong>m\u00e9todos anteriores<\/strong> s\u00f3lo se pod\u00edan tratar las <strong>varices peque\u00f1as y las grandes<\/strong> solamente eran tratadas a trav\u00e9s de la cirug\u00eda.<\/p><p>La <strong>sustituci\u00f3n del l\u00edquido por la espuma<\/strong> para <strong>tratar las varices<\/strong> constituy\u00f3 <strong>un paso muy grande en el tratamiento de venas varicosas<\/strong>, ya que la<strong> cirug\u00eda<\/strong> representa una forma <strong>traumatol\u00f3gica de eliminar varices<\/strong> para el paciente, <strong>a diferencia de este m\u00e9todo que fue<\/strong> desarrollado por el <strong>Dr. Mengual<\/strong> y sus compa\u00f1eros.<\/p><p>B\u00e1sicamente, el <strong>Doctor Mengual dio soluci\u00f3n al problema que ten\u00edan muchos pacientes<\/strong> al no querer someterse a una cirug\u00eda. Adem\u00e1s de que el <strong>tratamiento con microespuma es compatible con cualquier otro m\u00e9todo<\/strong> y con <strong>cualquier paciente sin importar edad.<\/strong><\/p><p>Comenzaron <strong>tratando las venas grandes como la safena<\/strong> y empezaron a<strong> tener \u00e9xito<\/strong> debido a que el proceso no requer\u00eda <strong>ni cirug\u00eda<\/strong>, ni <strong>cortes<\/strong>, <strong>ni anestesia<\/strong> y pod\u00eda llevarse a cabo <strong>sin hospitalizaci\u00f3n<\/strong>, o sea <em><strong>mucho mejor<\/strong><\/em>. A pesar de ser tres m\u00e9dicos trabajando en su inicio, <strong>no daban abasto para la cantidad de pacientes que comenzaron a tener<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44ab26a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44ab26a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a42cdec\" data-id=\"a42cdec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b908c4b elementor-widget elementor-widget-html\" data-id=\"b908c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"solovariz\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2e90d7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a2e90d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Solovariz<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a049aba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a049aba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ac6ded\" data-id=\"9ac6ded\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4964f7d elementor-widget elementor-widget-text-editor\" data-id=\"4964f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La idea de <strong>SOLOVARIZ<\/strong> parti\u00f3 del<strong> Doctor Mengual<\/strong> como un <strong>centro de formaci\u00f3n<\/strong> para <strong>todo profesional que quiera desarrollarse<\/strong> en el campo de la <strong>Medicina<\/strong> y ser parte del <strong>equipo de<\/strong> <strong>Centros<\/strong> donde se implementa la <strong>t\u00e9cnica de la eliminaci\u00f3n de varices con espuma<\/strong>, tambi\u00e9n conocidos como <strong>tratamientos FIVE<\/strong>.<\/p><p>Debido a que el <strong>Doctor Mengual<\/strong> es uno de los <strong>pioneros en este tipo de tratamiento<\/strong> pues quien mejor para <strong>ense\u00f1ar esta t\u00e9cnica<\/strong>. As\u00ed los pacientes no tendr\u00edan que desplazarse de un lugar a otro para tratarse y <strong>este tratamiento llegar\u00eda a toda Espa\u00f1a<\/strong>.<\/p><p>El <strong>Doctor Mengual<\/strong> en persona supervisa el <strong>proceso de admisi\u00f3n<\/strong> que permite a profesionales m\u00e9dicos de toda Espa\u00f1a abrir su centro <strong>SOLOVARIZ<\/strong> o concertar los <strong>SERVICIOS SOLOVARIZ<\/strong> en un centro que actualmente est\u00e9 ya abierto al P\u00fablico. En el <strong>desarrollo de la formaci\u00f3n de profesionales<\/strong> cuenta con <strong>prestigiosos y experimentados especialistas<\/strong> en cada campo de la medicina involucrados en el proceso del<strong> tratamiento<\/strong>.<\/p><p>Gracias al <strong>Doctor Mengual<\/strong> y sus compa\u00f1eros, todas las personas son capaces de <strong>acceder a un tratamiento<\/strong> que no presente <strong>ning\u00fan riesgo para su salud<\/strong>. Su <strong>trayectoria como m\u00e9dico<\/strong> as\u00ed como la <strong>seguridad<\/strong> y el <strong>alto grado de satisfacci\u00f3n de sus clientes<\/strong> es prueba del \u00e9xito de esta <strong>t\u00e9cnica desarrollada<\/strong> por ellos hace ya <strong>26 a\u00f1os<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ebc6c2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebc6c2f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2226064\" data-id=\"2226064\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-005c9b9 elementor-widget elementor-widget-html\" data-id=\"005c9b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"blog\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-961fe36 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"961fe36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Blog<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3065808 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3065808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22b23cb\" data-id=\"22b23cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d82968 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"2d82968\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1885 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual category-metodo-five\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/es-conveniente-operar-las-varices\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2021\/04\/es-conveniente-operar-las-varices-300x200.jpg\" class=\"attachment-medium size-medium wp-image-1887\" alt=\"\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2021\/04\/es-conveniente-operar-las-varices-300x200.jpg 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2021\/04\/es-conveniente-operar-las-varices-16x12.jpg 16w, https:\/\/solovariz.es\/wp-content\/uploads\/2021\/04\/es-conveniente-operar-las-varices.jpg 626w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/es-conveniente-operar-las-varices\/\" >\n\t\t\t\t\u00bfEs conveniente operar las varices?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfEs conveniente operar las varices? Las venas son vasos que llevan la sangre hacia el coraz\u00f3n. Cuando se alteran y no pueden hacerlo, sino que<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/es-conveniente-operar-las-varices\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfEs conveniente operar las varices?\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1293 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual category-metodo-five\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/ayudas-para-el-confinamiento-covid-19\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices-300x199.jpg\" class=\"attachment-medium size-medium wp-image-1186\" alt=\"\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices-300x199.jpg 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices.jpg 623w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/ayudas-para-el-confinamiento-covid-19\/\" >\n\t\t\t\tAyudas para el CONFINAMIENTO COVID-19\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Ayudas para el confinamiento. Ayudas para el CONFINAMIENTO COVID-19 Enumeramos\u00a0\u00a0algunas complicaciones que afectan a la circulaci\u00f3n de retorno, o sea, a las varices: No podemos<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/ayudas-para-el-confinamiento-covid-19\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Ayudas para el CONFINAMIENTO COVID-19\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1185 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/edad-que-aparecen-las-varices\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices-300x199.jpg\" class=\"attachment-medium size-medium wp-image-1186\" alt=\"\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices-300x199.jpg 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2020\/03\/\u00bfA-qu\u00e9-edad-aparecen-las-varices.jpg 623w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/edad-que-aparecen-las-varices\/\" >\n\t\t\t\t\u00bfA qu\u00e9 edad aparecen las varices?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfA qu\u00e9 edad aparecen las varices? En el art\u00edculo de hoy estaremos respondiendo a una de las interrogantes m\u00e1s comunes que se presenta en el<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/edad-que-aparecen-las-varices\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfA qu\u00e9 edad aparecen las varices?\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1179 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/varices-en-los-hombres\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/02\/Varices-en-hombres-300x195.jpg\" class=\"attachment-medium size-medium wp-image-1180\" alt=\"\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/02\/Varices-en-hombres-300x195.jpg 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2020\/02\/Varices-en-hombres.jpg 616w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/varices-en-los-hombres\/\" >\n\t\t\t\tVarices en los hombres\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Varices en los hombres La mayor parte de las veces las varices se han comentado como un tema que pr\u00e1cticamente afecta a la poblaci\u00f3n femenina,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/varices-en-los-hombres\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Varices en los hombres\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1163 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/cual-es-la-mejor-epoca-para-tratar-las-varices\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1-1-300x197.png\" class=\"attachment-medium size-medium wp-image-1164\" alt=\"Varices\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1-1-300x197.png 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1-1.png 689w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/cual-es-la-mejor-epoca-para-tratar-las-varices\/\" >\n\t\t\t\t\u00bfCu\u00e1l es la mejor \u00e9poca para tratar las varices?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfCu\u00e1l es la mejor \u00e9poca para tratar las varices? \u00bfCu\u00e1ntas veces te has preguntado cu\u00e1l es la mejor \u00e9poca del a\u00f1o para someterte a un<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/cual-es-la-mejor-epoca-para-tratar-las-varices\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfCu\u00e1l es la mejor \u00e9poca para tratar las varices?\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1155 post type-post status-publish format-standard has-post-thumbnail hentry category-doctor-mengual\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/solovariz.es\/es\/por-que-elegir-la-escleroterapia\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"290\" src=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1-300x290.png\" class=\"attachment-medium size-medium wp-image-1158\" alt=\"\" srcset=\"https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1-300x290.png 300w, https:\/\/solovariz.es\/wp-content\/uploads\/2020\/01\/1.png 316w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Doctor Mengual<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/solovariz.es\/es\/por-que-elegir-la-escleroterapia\/\" >\n\t\t\t\tPor qu\u00e9 elegir la escleroterapia\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por qu\u00e9 elegir la escleroterapia Como conocemos las varices es un problema que afecta a la gran mayor\u00eda de la poblaci\u00f3n, tanto a hombre como<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/solovariz.es\/es\/por-que-elegir-la-escleroterapia\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Por qu\u00e9 elegir la escleroterapia\" tabindex=\"-1\" >\n\t\t\tLeer M\u00e1s &gt;&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d969ae5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d969ae5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc6419a\" data-id=\"fc6419a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6416c68 elementor-widget elementor-widget-spacer\" data-id=\"6416c68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9d8170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9d8170\" data-element_type=\"section\" data-e-type=\"section\" id=\"entrevistas\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6.2,&quot;sizes&quot;:[]},&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1df11bb\" data-id=\"1df11bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b14eaee elementor-widget elementor-widget-html\" data-id=\"b14eaee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a id=\"tv\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193b0b6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"193b0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apariciones en televisi\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64315e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64315e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ac797f4\" data-id=\"ac797f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a2e794 elementor-widget elementor-widget-video\" data-id=\"6a2e794\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=fs5mFIlgKaU&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/1.jpg&quot;,&quot;id&quot;:1008,&quot;size&quot;:&quot;&quot;},&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/1.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01526b8 elementor-widget elementor-widget-text-editor\" data-id=\"01526b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Solovariz en Identidades<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b19505b\" data-id=\"b19505b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d3f67b elementor-widget elementor-widget-video\" data-id=\"6d3f67b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=j2lxWDEkcTo&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/2-SOLOVARIZ-en-Madrid-Directo-Telemadrid-YouTube-Google-Chrome.jpg&quot;,&quot;id&quot;:1010,&quot;size&quot;:&quot;&quot;},&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/2-SOLOVARIZ-en-Madrid-Directo-Telemadrid-YouTube-Google-Chrome.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d0183a elementor-widget elementor-widget-text-editor\" data-id=\"0d0183a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Solovariz en Madrid Directo Telemadrid<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-df83fb7\" data-id=\"df83fb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4dfa4e elementor-widget elementor-widget-video\" data-id=\"a4dfa4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=LQjmqxYI35M&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Qu\\u00e9-son-las-varices-Tu-TV-Videos-de-Ciencia-y-Tecnolog\\u00eda-YouTube-Google-Chrome.jpg&quot;,&quot;id&quot;:1039,&quot;size&quot;:&quot;&quot;},&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/Qu\u00e9-son-las-varices-Tu-TV-Videos-de-Ciencia-y-Tecnolog\u00eda-YouTube-Google-Chrome.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9ca098 elementor-widget elementor-widget-text-editor\" data-id=\"b9ca098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Qu\u00e9 son las varices &#8211; \u00abTu TV\u00bb &#8211; Videos de Ciencia y Tecnolog\u00eda<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ae8c8f6\" data-id=\"ae8c8f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96ddc10 elementor-widget elementor-widget-video\" data-id=\"96ddc10\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=V5cG3bVCRnE&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/3-SOLOVARIZ-en-Saber-Vivir-en-La-ma\\u00f1ana-de-la-1-YouTube-Google-Chrome.jpg&quot;,&quot;id&quot;:1012,&quot;size&quot;:&quot;&quot;},&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/3-SOLOVARIZ-en-Saber-Vivir-en-La-ma\u00f1ana-de-la-1-YouTube-Google-Chrome.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5a50c elementor-widget elementor-widget-text-editor\" data-id=\"5e5a50c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Saber Vivir en La ma\u00f1ana de la 1<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0618d79\" data-id=\"0618d79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7aa0d5 elementor-widget elementor-widget-video\" data-id=\"f7aa0d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=uwaKcy1kadk&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/SOLOVARIZ-en-Noticias-de-la-2-YouTube-Google-Chrome.jpg&quot;,&quot;id&quot;:1040,&quot;size&quot;:&quot;&quot;},&quot;lazy_load&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/solovariz.es\/wp-content\/uploads\/2019\/04\/SOLOVARIZ-en-Noticias-de-la-2-YouTube-Google-Chrome.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9daee3 elementor-widget elementor-widget-text-editor\" data-id=\"e9daee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Noticias de la 2<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Doctor Juan Jos\u00e9 Mengual Miembro fundador en Centro De Estudios Flebol\u00f3gicos y Grupo Solovariz Historia El Dr. Juan Jos\u00e9 Mengual comenz\u00f3 a estudiar Medicina en la Universidad Complutense de Madrid, en 1970.. Seguir leyendo Centro de Estudios Flebol\u00f3gicos Espec\u00edficamente en el a\u00f1o 1993, se encontraron frente al m\u00e9todo del tratamiento de varices con espuma.. Seguir [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-978","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solovariz.es\/es\/doctor-juan-jose-mengual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices\" \/>\n<meta property=\"og:description\" content=\"Doctor Juan Jos\u00e9 Mengual Miembro fundador en Centro De Estudios Flebol\u00f3gicos y Grupo Solovariz Historia El Dr. Juan Jos\u00e9 Mengual comenz\u00f3 a estudiar Medicina en la Universidad Complutense de Madrid, en 1970.. Seguir leyendo Centro de Estudios Flebol\u00f3gicos Espec\u00edficamente en el a\u00f1o 1993, se encontraron frente al m\u00e9todo del tratamiento de varices con espuma.. Seguir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solovariz.es\/es\/doctor-juan-jose-mengual\/\" \/>\n<meta property=\"og:site_name\" content=\"Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solovariz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T08:59:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@solovariz\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solovariz.es\\\/doctor-juan-jose-mengual\\\/\",\"url\":\"https:\\\/\\\/solovariz.es\\\/doctor-juan-jose-mengual\\\/\",\"name\":\"Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#website\"},\"datePublished\":\"2019-04-11T10:39:38+00:00\",\"dateModified\":\"2026-03-17T08:59:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solovariz.es\\\/doctor-juan-jose-mengual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solovariz.es\\\/doctor-juan-jose-mengual\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solovariz.es\\\/doctor-juan-jose-mengual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/solovariz.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctor Juan Jose Mengual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/solovariz.es\\\/es\\\/\",\"name\":\"Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices\",\"description\":\"M\u00c9DICOS COMPROMETIDOS CON SUS VARICES\",\"publisher\":{\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solovariz.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#organization\",\"name\":\"Solovariz\",\"url\":\"https:\\\/\\\/solovariz.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logotipo_1.png\",\"contentUrl\":\"https:\\\/\\\/solovariz.es\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logotipo_1.png\",\"width\":260,\"height\":354,\"caption\":\"Solovariz\"},\"image\":{\"@id\":\"https:\\\/\\\/solovariz.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solovariz\",\"https:\\\/\\\/x.com\\\/solovariz\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgGfDCyXBZr6Ln8Tv4mFxbA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solovariz.es\/es\/doctor-juan-jose-mengual\/","og_locale":"es_ES","og_type":"article","og_title":"Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices","og_description":"Doctor Juan Jos\u00e9 Mengual Miembro fundador en Centro De Estudios Flebol\u00f3gicos y Grupo Solovariz Historia El Dr. Juan Jos\u00e9 Mengual comenz\u00f3 a estudiar Medicina en la Universidad Complutense de Madrid, en 1970.. Seguir leyendo Centro de Estudios Flebol\u00f3gicos Espec\u00edficamente en el a\u00f1o 1993, se encontraron frente al m\u00e9todo del tratamiento de varices con espuma.. Seguir [&hellip;]","og_url":"https:\/\/solovariz.es\/es\/doctor-juan-jose-mengual\/","og_site_name":"Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices","article_publisher":"https:\/\/www.facebook.com\/Solovariz","article_modified_time":"2026-03-17T08:59:54+00:00","twitter_card":"summary_large_image","twitter_site":"@solovariz","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solovariz.es\/doctor-juan-jose-mengual\/","url":"https:\/\/solovariz.es\/doctor-juan-jose-mengual\/","name":"Doctor Juan Jose Mengual | Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices","isPartOf":{"@id":"https:\/\/solovariz.es\/es\/#website"},"datePublished":"2019-04-11T10:39:38+00:00","dateModified":"2026-03-17T08:59:54+00:00","breadcrumb":{"@id":"https:\/\/solovariz.es\/doctor-juan-jose-mengual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solovariz.es\/doctor-juan-jose-mengual\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solovariz.es\/doctor-juan-jose-mengual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/solovariz.es\/"},{"@type":"ListItem","position":2,"name":"Doctor Juan Jose Mengual"}]},{"@type":"WebSite","@id":"https:\/\/solovariz.es\/es\/#website","url":"https:\/\/solovariz.es\/es\/","name":"Solovariz - Cl\u00ednicas especializadas en eliminar todo tipo de varices","description":"M\u00c9DICOS COMPROMETIDOS CON SUS VARICES","publisher":{"@id":"https:\/\/solovariz.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solovariz.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/solovariz.es\/es\/#organization","name":"Solovariz","url":"https:\/\/solovariz.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solovariz.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/solovariz.es\/wp-content\/uploads\/2018\/02\/logotipo_1.png","contentUrl":"https:\/\/solovariz.es\/wp-content\/uploads\/2018\/02\/logotipo_1.png","width":260,"height":354,"caption":"Solovariz"},"image":{"@id":"https:\/\/solovariz.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solovariz","https:\/\/x.com\/solovariz","https:\/\/www.youtube.com\/channel\/UCgGfDCyXBZr6Ln8Tv4mFxbA"]}]}},"_links":{"self":[{"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/pages\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":42,"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/pages\/978\/revisions"}],"predecessor-version":[{"id":2430,"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/pages\/978\/revisions\/2430"}],"wp:attachment":[{"href":"https:\/\/solovariz.es\/es\/wp-json\/wp\/v2\/media?parent=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}